{"id":513,"date":"2021-01-01T11:37:00","date_gmt":"2021-01-01T19:37:00","guid":{"rendered":"https:\/\/blogs.mulesoft.com\/de\/?p=513"},"modified":"2023-02-20T22:02:53","modified_gmt":"2023-02-20T22:02:53","slug":"align-organization-and-culture","status":"publish","type":"post","link":"https:\/\/blogs.mulesoft.com\/de\/digitale-strategie-digitale-transformation\/align-organization-and-culture\/","title":{"rendered":"Digitale Transformation: Bringen Sie Unternehmen und Kultur auf Kurs"},"content":{"rendered":"<span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Reading Time: <\/span> <span class=\"rt-time\"> 7<\/span> <span class=\"rt-label rt-postfix\">minutes<\/span><\/span>\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u201eWenn eine Organisation ein System entwirft, wird dessen Design die interne Kommunikationsstruktur abbilden.\u201c<\/p>\n<\/blockquote>\n\n\n\n<p><em>\u2013&nbsp;Mel Conway<\/em><\/p>\n\n\n\n<!--more-->\n\n\n\n<p>Eine der gr\u00f6\u00dften Herausforderungen bei der digitalen Transformation ist die Abstimmung Ihrer Organisationsstruktur, Unternehmenskultur und Arbeitsweisen auf Ihre digitale Strategie. Im Idealfall sind Technik-, Produkt- und Unternehmensbereiche so organisiert, dass sie auf neue Marktchancen reagieren k\u00f6nnen \u2013 und die Unternehmenskultur treibt sie wie ein atlantischer Passatwind voran. In gro\u00dfen Organisationen halten aber vielmehr kulturelle Barrieren die Teams in einer Flaute gefangen und hindern sie am Vorankommen.<\/p>\n\n\n\n<p>Viele in der <a href=\"https:\/\/www.mulesoft.com\/de\/resources\/api\/what-is-an-api-economy\" target=\"_blank\" rel=\"noreferrer noopener\">API Economy<\/a> f\u00fchrende Unternehmen haben einen Paradigmenwechsel f\u00fcr die Bereitstellung ihrer digitalen Produkte vollzogen. Dieser umfasst im Wesentlichen agile-Entwicklungsmethoden, eine DevOps-Mentalit\u00e4t, Cloud-native Technologien, eine Microservices-Architektur und <a href=\"https:\/\/www.mulesoft.com\/de\/lp\/whitepaper\/api\/api-led-connectivity\" target=\"_blank\" rel=\"noreferrer noopener\">API-gesteuerte Konnektivit\u00e4t<\/a>. Mit diesem API-orientierten Ansatz konnten solche Unternehmen trotz astronomischer Gesch\u00e4ftsexpansion extrem innovativ und operativ stabil bleiben. Folgen Organisationen dieser Praxis, werden sie im Laufe der Zeit die Unternehmenskultur in eine neue Richtung lenken k\u00f6nnen.<\/p>\n\n\n\n<p>Eine der wirkungsvollsten Methoden zum \u00c4ndern der Unternehmenskultur ist zugleich die einfachste. Das Festlegen von Prinzipien und das Vorleben dieser Prinzipien vermittelt der Belegschaft eindeutig, worauf es ankommt. Je klarer die F\u00fchrungsebene die Prinzipien der digitalen Transformation kommuniziert und verk\u00f6rpert, desto mehr Mitarbeiter:innen werden sie ebenfalls verinnerlichen. Dann k\u00f6nnen Entscheidungen schneller und auf niedrigeren Ebenen getroffen werden.<\/p>\n\n\n\n<p>Die 12 F\u00fchrungsprinzipien von Amazon sind tief in der Organisation verankert und spiegeln sich in den t\u00e4glichen Gesch\u00e4ftsabl\u00e4ufen und bei Bewerbungsgespr\u00e4chen wider. Wenn Prinzipien ein Unternehmen so durchdringen, kann es deutlich eher agil und auf breiter Basis innovativ werden.<\/p>\n\n\n\n<p>Eine weitere bew\u00e4hrte Methode zum Einbeziehen der Unternehmenskultur ist das Schaffen von Anreizen zur Selbststeuerung. In der Vergangenheit neigten IT-Abteilungen gro\u00dfer Unternehmen zu einer rigide von oben nach unten gerichteten Kontrolle. Sie diktieren den Entwicklungs- oder Technikerteams: \u201eBefolgt diesen Standard oder verwendet dieses Framework, sonst&#8230;!\u201c Unternehmensstandards sind in einigen F\u00e4llen durchaus sinnvoll. Es entstehen aber deutlich weniger Reibungen, wenn Sie Ihrer Belegschaft zeigen, wie Sie die Dinge gerne h\u00e4tten, wenn Sie erkl\u00e4ren, warum der von Ihnen vertretene Ansatz vern\u00fcnftig ist, und wenn Sie Tools und Dokumentationen f\u00fcr das einfache Befolgen Ihrer Richtlinien anbieten. Wenn das gelingt, steuern Software-Engineers und -Entwickler:innen sich irgendwann selbst durch permanente Selbstreflexion: \u201eIst das, was ich tue, das, was ich tun m\u00f6chte oder sollte?\u201c<\/p>\n\n\n\n<p>Zwar eignet sich eine Umstrukturierung nur bedingt zur Ver\u00e4nderung der Unternehmenskultur, m\u00f6glicherweise m\u00fcssen Sie aber f\u00fcr eine agilere Systementwicklung die organisatorischen Abl\u00e4ufe ein St\u00fcck weit anpassen. Unternehmen, die an gro\u00dfe, monolithische Produkt-Releases gew\u00f6hnt sind, sollten ihre Entwicklungsteams auf schnellere Release-Zyklen umstellen, die einer hohen Frequenz von \u00c4nderungen entsprechen. Best Practice in der heutigen Softwareindustrie ist eine schnellen Abfolge kleiner Anpassungen. Das ersetzt die seit Jahrzehnten \u00fcblichen gro\u00dfen Produktivversionen, auf die nur allzu oft mehrere Runden mit Fehlerbehebungen und Notpatches folgten. Anstatt Ver\u00e4nderungen zu f\u00fcrchten, wollen Unternehmen sie heute bestm\u00f6glich meistern.<\/p>\n\n\n\n<p>Parallel zu den schnelleren Versionszyklen ist eine Pipeline-Bereitstellung erforderlich. Je mehr sie hier automatisieren k\u00f6nnen, desto besser.<\/p>\n\n\n\n<p>Zur Unterst\u00fctzung dieser neuen Entwicklungspraktiken sollten Sie eine Kultur des Experimentierens und Lernens pflegen. Einige Betriebskonzepte und Releases werden sicher M\u00e4ngel aufweisen. Aber in Verbindung mit schnellen Feedbackschleifen er\u00f6ffnen Fehler eine weitere Chance f\u00fcr Ihre Unternehmenstransformation.<\/p>\n\n\n\n<p>Eine abschlie\u00dfende Empfehlung, um Ihre Unternehmensabl\u00e4ufe und -kultur mit Ihrer digitalen Strategie in Einklang zu bringen: Probieren Sie \u201edomain-driven Design\u201c aus. Dieser Ansatz wurde im Kontext der Microservices-Bewegung als Alternative zu den eher monolithischen, UI-basierten Ans\u00e4tzen popul\u00e4r und betrachtet Systeme aus der Perspektive von Business Domains. Wenn Sie DDD in einem API-Kontext anwenden, k\u00f6nnen Sie ein System auf Basis der Interaktionen zwischen den Komponenten modellieren. So erhalten Sie eine API-basierte Architektur, die sich viel leichter als mit herk\u00f6mmlichen Methoden an Ihre Gesch\u00e4ftsanforderungen anpassen l\u00e4sst.<\/p>\n\n\n\n<p>Die &nbsp;<a href=\"https:\/\/www.mulesoft.com\/de\/demo\/anypoint-platform-deep-dive\" target=\"_blank\" rel=\"noreferrer noopener\">API-Programm-Workshops<\/a> von MuleSoft helfen Unternehmen beim Ausrichten ihrer organisatorischen Strukturen und Firmenkultur auf die digitale Transformation. Informieren Sie sich \u00fcber den Aufbau einer API-Strategie, die Betreuung von Entwickler-\u00d6kosystemen und mehr.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201eWenn eine Organisation ein System entwirft, wird dessen Design die interne Kommunikationsstruktur abbilden.\u201c \u2013&nbsp;Mel Conway<\/p>\n","protected":false},"author":5131,"featured_media":512,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[290],"tags":[93,82],"series":[213],"persona":[],"industry":[],"class_list":["post-513","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-digitale-strategie-digitale-transformation","tag-digital-transformation","tag-api-strategy","series-digital-transformation-strategy"],"acf":[],"aioseo_notices":[],"jetpack_featured_media_url":"https:\/\/blogs.mulesoft.com\/de\/wp-content\/uploads\/sites\/3\/ninja.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/blogs.mulesoft.com\/de\/wp-json\/wp\/v2\/posts\/513","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.mulesoft.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.mulesoft.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.mulesoft.com\/de\/wp-json\/wp\/v2\/users\/5131"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.mulesoft.com\/de\/wp-json\/wp\/v2\/comments?post=513"}],"version-history":[{"count":3,"href":"https:\/\/blogs.mulesoft.com\/de\/wp-json\/wp\/v2\/posts\/513\/revisions"}],"predecessor-version":[{"id":976,"href":"https:\/\/blogs.mulesoft.com\/de\/wp-json\/wp\/v2\/posts\/513\/revisions\/976"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.mulesoft.com\/de\/wp-json\/wp\/v2\/media\/512"}],"wp:attachment":[{"href":"https:\/\/blogs.mulesoft.com\/de\/wp-json\/wp\/v2\/media?parent=513"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.mulesoft.com\/de\/wp-json\/wp\/v2\/categories?post=513"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.mulesoft.com\/de\/wp-json\/wp\/v2\/tags?post=513"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/blogs.mulesoft.com\/de\/wp-json\/wp\/v2\/series?post=513"},{"taxonomy":"persona","embeddable":true,"href":"https:\/\/blogs.mulesoft.com\/de\/wp-json\/wp\/v2\/persona?post=513"},{"taxonomy":"industry","embeddable":true,"href":"https:\/\/blogs.mulesoft.com\/de\/wp-json\/wp\/v2\/industry?post=513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}